{"id":15342,"date":"2016-09-20T04:37:14","date_gmt":"2016-09-20T04:36:45","guid":{"rendered":"https:\/\/www.exotravel.com\/blog\/?p=15342"},"modified":"2016-09-20T09:42:58","modified_gmt":"2016-09-20T09:42:58","slug":"norte-de-tailandia-belleza-natural-e-historia-5-dias-4-noches","status":"publish","type":"post","link":"https:\/\/www.exotravel.com\/blog\/norte-de-tailandia-belleza-natural-e-historia-5-dias-4-noches\/","title":{"rendered":"Norte de Tailandia &#8211; Belleza Natural e Historia (5 D\u00edas \/ 4 Noches)"},"content":{"rendered":"<p>Tailandia es un destino fundamental en los viajes al sureste asi\u00e1tico y quien lo visita normalmente quiere conocer el norte pintoresco. El hecho de ser una zona conocida, sin embargo, no ha diluido el impacto visual de este tranquilo rinc\u00f3n de Asia. Adem\u00e1s, mientras que la capital del norte, Chiang Mai, es muy visitada, existen otras partes de la regi\u00f3n con un n\u00famero de visitantes mucho menor. Esta propuesta muestra los paisajes y culturas relativamente desconocidas en provincias como Chiang Rai, Nan y Phitsanulok. En el extremo norte, los viajeros podr\u00e1n disfrutar de encuentros con tribus locales, aprender los secretos de la artesan\u00eda Hmong y podr\u00e1n participar en actividades de concientizaci\u00f3n ecol\u00f3gica como la plantaci\u00f3n de hierbas. Pasando a trav\u00e9s de incre\u00edbles paisajes, el camino se dirige hacia el sur antes de finalizar en Sukhothai, antigua capital de Tailandia, conocida por sus evocadoras ruinas.<\/p>\n<p>Para m\u00e1s informaci\u00f3n, p\u00f3ngase en contacto con uno de nuestros expertos asesores de viajes en <a href=\"mailto:thailand@exotravel.com\"><strong>thailand@exotravel.com<\/strong><\/a> o <a href=\"http:\/\/traveltrade.exotravel.com\/product\/northern-thailand-natural-beauty-and-history\/\"><strong>vea el itinerario completo aqu\u00ed<\/strong><\/a><strong>.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tailandia es un destino fundamental en los viajes al sureste asi\u00e1tico y quien lo visita normalmente quiere conocer el norte pintoresco. El hecho de ser una zona conocida, sin embargo, no ha diluido el impacto visual de este tranquilo rinc\u00f3n de Asia. Adem\u00e1s, mientras que la capital del norte, Chiang Mai, es muy visitada, existen [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":15429,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[658,769,775],"tags":[],"class_list":["post-15342","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arte-y-cultura","category-placer-y-hacer","category-tailandia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Norte de Tailandia - Belleza Natural e Historia (5 D\u00edas \/ 4 Noches) - EXO Travel Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.exotravel.com\/blog\/es\/norte-de-tailandia-belleza-natural-e-historia-5-dias-4-noches\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Norte de Tailandia - Belleza Natural e Historia (5 D\u00edas \/ 4 Noches) - EXO Travel Blog\" \/>\n<meta property=\"og:description\" content=\"Tailandia es un destino fundamental en los viajes al sureste asi\u00e1tico y quien lo visita normalmente quiere conocer el norte pintoresco. El hecho de ser una zona conocida, sin embargo, no ha diluido el impacto visual de este tranquilo rinc\u00f3n de Asia. Adem\u00e1s, mientras que la capital del norte, Chiang Mai, es muy visitada, existen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.exotravel.com\/blog\/es\/norte-de-tailandia-belleza-natural-e-historia-5-dias-4-noches\/\" \/>\n<meta property=\"og:site_name\" content=\"EXO Travel Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExoTravelGroup\" \/>\n<meta property=\"article:published_time\" content=\"2016-09-20T04:36:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-09-20T09:42:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2016\/09\/shutterstock_175933862-Sukhothai-1024x472.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"472\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EXO_Travel\" \/>\n<meta name=\"twitter:site\" content=\"@EXO_Travel\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/es\\\/norte-de-tailandia-belleza-natural-e-historia-5-dias-4-noches\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/es\\\/norte-de-tailandia-belleza-natural-e-historia-5-dias-4-noches\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Norte de Tailandia &#8211; Belleza Natural e Historia (5 D\u00edas \\\/ 4 Noches)\",\"datePublished\":\"2016-09-20T04:36:45+00:00\",\"dateModified\":\"2016-09-20T09:42:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/es\\\/norte-de-tailandia-belleza-natural-e-historia-5-dias-4-noches\\\/\"},\"wordCount\":195,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/es\\\/norte-de-tailandia-belleza-natural-e-historia-5-dias-4-noches\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/shutterstock_175933862-Sukhothai.jpg\",\"articleSection\":[\"Arte y Cultura\",\"PLACER Y HACER\",\"Tailandia\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/es\\\/norte-de-tailandia-belleza-natural-e-historia-5-dias-4-noches\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/es\\\/norte-de-tailandia-belleza-natural-e-historia-5-dias-4-noches\\\/\",\"url\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/es\\\/norte-de-tailandia-belleza-natural-e-historia-5-dias-4-noches\\\/\",\"name\":\"Norte de Tailandia - Belleza Natural e Historia (5 D\u00edas \\\/ 4 Noches) - EXO Travel Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/es\\\/norte-de-tailandia-belleza-natural-e-historia-5-dias-4-noches\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/es\\\/norte-de-tailandia-belleza-natural-e-historia-5-dias-4-noches\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/shutterstock_175933862-Sukhothai.jpg\",\"datePublished\":\"2016-09-20T04:36:45+00:00\",\"dateModified\":\"2016-09-20T09:42:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/es\\\/norte-de-tailandia-belleza-natural-e-historia-5-dias-4-noches\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/es\\\/norte-de-tailandia-belleza-natural-e-historia-5-dias-4-noches\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/es\\\/norte-de-tailandia-belleza-natural-e-historia-5-dias-4-noches\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/shutterstock_175933862-Sukhothai.jpg\",\"contentUrl\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/shutterstock_175933862-Sukhothai.jpg\",\"width\":10914,\"height\":5028},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/es\\\/norte-de-tailandia-belleza-natural-e-historia-5-dias-4-noches\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Norte de Tailandia &#8211; Belleza Natural e Historia (5 D\u00edas \\\/ 4 Noches)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/\",\"name\":\"EXO Travel Blog\",\"description\":\"Travel Made Real\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/#organization\",\"name\":\"EXO Travel Group\",\"url\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Classic-Journeys-1.png\",\"contentUrl\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Classic-Journeys-1.png\",\"width\":900,\"height\":350,\"caption\":\"EXO Travel Group\"},\"image\":{\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ExoTravelGroup\",\"https:\\\/\\\/x.com\\\/EXO_Travel\",\"https:\\\/\\\/www.instagram.com\\\/exotravelgroup\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/exotravel\",\"https:\\\/\\\/www.pinterest.com\\\/exotravel\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/exotravel\"]},{\"@type\":\"Person\",\"@id\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Norte de Tailandia - Belleza Natural e Historia (5 D\u00edas \/ 4 Noches) - EXO Travel Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.exotravel.com\/blog\/es\/norte-de-tailandia-belleza-natural-e-historia-5-dias-4-noches\/","og_locale":"en_GB","og_type":"article","og_title":"Norte de Tailandia - Belleza Natural e Historia (5 D\u00edas \/ 4 Noches) - EXO Travel Blog","og_description":"Tailandia es un destino fundamental en los viajes al sureste asi\u00e1tico y quien lo visita normalmente quiere conocer el norte pintoresco. El hecho de ser una zona conocida, sin embargo, no ha diluido el impacto visual de este tranquilo rinc\u00f3n de Asia. Adem\u00e1s, mientras que la capital del norte, Chiang Mai, es muy visitada, existen [&hellip;]","og_url":"https:\/\/www.exotravel.com\/blog\/es\/norte-de-tailandia-belleza-natural-e-historia-5-dias-4-noches\/","og_site_name":"EXO Travel Blog","article_publisher":"https:\/\/www.facebook.com\/ExoTravelGroup","article_published_time":"2016-09-20T04:36:45+00:00","article_modified_time":"2016-09-20T09:42:58+00:00","og_image":[{"width":1024,"height":472,"url":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2016\/09\/shutterstock_175933862-Sukhothai-1024x472.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@EXO_Travel","twitter_site":"@EXO_Travel","twitter_misc":{"Written by":"","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.exotravel.com\/blog\/es\/norte-de-tailandia-belleza-natural-e-historia-5-dias-4-noches\/#article","isPartOf":{"@id":"https:\/\/www.exotravel.com\/blog\/es\/norte-de-tailandia-belleza-natural-e-historia-5-dias-4-noches\/"},"author":{"name":"","@id":""},"headline":"Norte de Tailandia &#8211; Belleza Natural e Historia (5 D\u00edas \/ 4 Noches)","datePublished":"2016-09-20T04:36:45+00:00","dateModified":"2016-09-20T09:42:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.exotravel.com\/blog\/es\/norte-de-tailandia-belleza-natural-e-historia-5-dias-4-noches\/"},"wordCount":195,"commentCount":0,"publisher":{"@id":"https:\/\/www.exotravel.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.exotravel.com\/blog\/es\/norte-de-tailandia-belleza-natural-e-historia-5-dias-4-noches\/#primaryimage"},"thumbnailUrl":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2016\/09\/shutterstock_175933862-Sukhothai.jpg","articleSection":["Arte y Cultura","PLACER Y HACER","Tailandia"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.exotravel.com\/blog\/es\/norte-de-tailandia-belleza-natural-e-historia-5-dias-4-noches\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.exotravel.com\/blog\/es\/norte-de-tailandia-belleza-natural-e-historia-5-dias-4-noches\/","url":"https:\/\/www.exotravel.com\/blog\/es\/norte-de-tailandia-belleza-natural-e-historia-5-dias-4-noches\/","name":"Norte de Tailandia - Belleza Natural e Historia (5 D\u00edas \/ 4 Noches) - EXO Travel Blog","isPartOf":{"@id":"https:\/\/www.exotravel.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.exotravel.com\/blog\/es\/norte-de-tailandia-belleza-natural-e-historia-5-dias-4-noches\/#primaryimage"},"image":{"@id":"https:\/\/www.exotravel.com\/blog\/es\/norte-de-tailandia-belleza-natural-e-historia-5-dias-4-noches\/#primaryimage"},"thumbnailUrl":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2016\/09\/shutterstock_175933862-Sukhothai.jpg","datePublished":"2016-09-20T04:36:45+00:00","dateModified":"2016-09-20T09:42:58+00:00","breadcrumb":{"@id":"https:\/\/www.exotravel.com\/blog\/es\/norte-de-tailandia-belleza-natural-e-historia-5-dias-4-noches\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.exotravel.com\/blog\/es\/norte-de-tailandia-belleza-natural-e-historia-5-dias-4-noches\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.exotravel.com\/blog\/es\/norte-de-tailandia-belleza-natural-e-historia-5-dias-4-noches\/#primaryimage","url":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2016\/09\/shutterstock_175933862-Sukhothai.jpg","contentUrl":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2016\/09\/shutterstock_175933862-Sukhothai.jpg","width":10914,"height":5028},{"@type":"BreadcrumbList","@id":"https:\/\/www.exotravel.com\/blog\/es\/norte-de-tailandia-belleza-natural-e-historia-5-dias-4-noches\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.exotravel.com\/blog\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Norte de Tailandia &#8211; Belleza Natural e Historia (5 D\u00edas \/ 4 Noches)"}]},{"@type":"WebSite","@id":"https:\/\/www.exotravel.com\/blog\/#website","url":"https:\/\/www.exotravel.com\/blog\/","name":"EXO Travel Blog","description":"Travel Made Real","publisher":{"@id":"https:\/\/www.exotravel.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.exotravel.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.exotravel.com\/blog\/#organization","name":"EXO Travel Group","url":"https:\/\/www.exotravel.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.exotravel.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2020\/02\/Classic-Journeys-1.png","contentUrl":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2020\/02\/Classic-Journeys-1.png","width":900,"height":350,"caption":"EXO Travel Group"},"image":{"@id":"https:\/\/www.exotravel.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ExoTravelGroup","https:\/\/x.com\/EXO_Travel","https:\/\/www.instagram.com\/exotravelgroup","https:\/\/www.linkedin.com\/company\/exotravel","https:\/\/www.pinterest.com\/exotravel\/","https:\/\/www.youtube.com\/user\/exotravel"]},{"@type":"Person","@id":""}]}},"_links":{"self":[{"href":"https:\/\/www.exotravel.com\/blog\/wp-json\/wp\/v2\/posts\/15342","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.exotravel.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.exotravel.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.exotravel.com\/blog\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.exotravel.com\/blog\/wp-json\/wp\/v2\/comments?post=15342"}],"version-history":[{"count":0,"href":"https:\/\/www.exotravel.com\/blog\/wp-json\/wp\/v2\/posts\/15342\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.exotravel.com\/blog\/wp-json\/wp\/v2\/media\/15429"}],"wp:attachment":[{"href":"https:\/\/www.exotravel.com\/blog\/wp-json\/wp\/v2\/media?parent=15342"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.exotravel.com\/blog\/wp-json\/wp\/v2\/categories?post=15342"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.exotravel.com\/blog\/wp-json\/wp\/v2\/tags?post=15342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}