{"id":14027,"date":"2015-05-22T02:06:52","date_gmt":"2015-05-22T02:06:52","guid":{"rendered":"https:\/\/www.exotravel.com\/blog\/?p=14027"},"modified":"2016-02-09T02:07:42","modified_gmt":"2016-02-09T02:07:42","slug":"nouveau-circuit-myanmar-la-plus-belle-des-aventures-en-famille-au-myanmar-10-jours-9-nuits-2","status":"publish","type":"post","link":"https:\/\/www.exotravel.com\/blog\/fr\/nouveau-circuit-myanmar-la-plus-belle-des-aventures-en-famille-au-myanmar-10-jours-9-nuits-2\/","title":{"rendered":"Nouveau Circuit Myanmar: La plus belle des aventures en famille au Myanmar (10 Jours \/ 9 Nuits)"},"content":{"rendered":"<p style=\"text-align: left;\">Le Myanmar est l\u2019un des pays les plus beaux et les plus passionnants de la r\u00e9gion. C\u2019est le choix de vacances id\u00e9al des familles qui veulent sortir des sentiers battus. Coup\u00e9 du monde pendant des d\u00e9cennies, le pays s\u2019est ouvert r\u00e9cemment et se revendique aujourd\u2019hui comme une destination touristique majeure.<\/p>\n<p>Bien que la vie moderne soit en train d\u2019arriver avec l\u2019ouverture de nouveaux h\u00f4tels, la construction de grands immeubles, les ann\u00e9es d\u2019isolement ont permis de conserver de pr\u00e9cieux \u00e9l\u00e9ments de la culture birmane. Dans l\u2019ancienne capitale Yangon, il ne faut pas manquer de visiter l\u2019incroyable Pagode Shwedagon comme les quartiers de Little India et de Chinatown qui grouillent de vie et d\u2019activit\u00e9s.<\/p>\n<p>En dehors des villes, le reste du pays est tout aussi enthousiasmant. Le tranquille lac Inl\u00e9 est l\u2019un des sites majeurs du pays. Moins connues mais tout aussi captivantes, les randonn\u00e9es dans les montagnes du pays Shan et les sessions de m\u00e9ditation pr\u00e8s de la ville l\u00e9gendaire de Mandalay.<\/p>\n<p>Prenez contact avec<strong> <a href=\"mailto;adventure@exotravel.com \" target=\"_blank\">adventure@exotravel.com <\/a><\/strong>pour satisfaire toutes vos envies de sensations fortes ou obtenez tous les d\u00e9tails sur ce voyage en explorant <strong><a href=\"http:\/\/traveltrade.exotravel.com\/product\/myanmars-finest-family-adventure\/\" target=\"_blank\">l\u2019itin\u00e9raire complet.<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Myanmar est l\u2019un des pays les plus beaux et les plus passionnants de la r\u00e9gion. C\u2019est le choix de vacances id\u00e9al des familles qui veulent sortir des sentiers battus. Coup\u00e9 du monde pendant des d\u00e9cennies, le pays s\u2019est ouvert r\u00e9cemment et se revendique aujourd\u2019hui comme une destination touristique majeure. Bien que la vie moderne [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11282,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[650,703,749],"tags":[],"class_list":["post-14027","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aventure","category-famille","category-myanmar-francais"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Myanmar\u2019s Finest Family Adventure (10 Days \/ 9 Nights)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.exotravel.com\/blog\/fr\/nouveau-circuit-myanmar-la-plus-belle-des-aventures-en-famille-au-myanmar-10-jours-9-nuits-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Myanmar\u2019s Finest Family Adventure (10 Days \/ 9 Nights)\" \/>\n<meta property=\"og:description\" content=\"Le Myanmar est l\u2019un des pays les plus beaux et les plus passionnants de la r\u00e9gion. C\u2019est le choix de vacances id\u00e9al des familles qui veulent sortir des sentiers battus. Coup\u00e9 du monde pendant des d\u00e9cennies, le pays s\u2019est ouvert r\u00e9cemment et se revendique aujourd\u2019hui comme une destination touristique majeure. Bien que la vie moderne [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.exotravel.com\/blog\/fr\/nouveau-circuit-myanmar-la-plus-belle-des-aventures-en-famille-au-myanmar-10-jours-9-nuits-2\/\" \/>\n<meta property=\"og:site_name\" content=\"EXO Travel Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExoTravelGroup\" \/>\n<meta property=\"article:published_time\" content=\"2015-05-22T02:06:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-02-09T02:07:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2015\/05\/Golden-Rock.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"580\" \/>\n\t<meta property=\"og:image:height\" content=\"386\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EXO_Travel\" \/>\n<meta name=\"twitter:site\" content=\"@EXO_Travel\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/fr\\\/nouveau-circuit-myanmar-la-plus-belle-des-aventures-en-famille-au-myanmar-10-jours-9-nuits-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/fr\\\/nouveau-circuit-myanmar-la-plus-belle-des-aventures-en-famille-au-myanmar-10-jours-9-nuits-2\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/#\\\/schema\\\/person\\\/25f31f713ccd2c645ee56d896fb33fc0\"},\"headline\":\"Nouveau Circuit Myanmar: La plus belle des aventures en famille au Myanmar (10 Jours \\\/ 9 Nuits)\",\"datePublished\":\"2015-05-22T02:06:52+00:00\",\"dateModified\":\"2016-02-09T02:07:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/fr\\\/nouveau-circuit-myanmar-la-plus-belle-des-aventures-en-famille-au-myanmar-10-jours-9-nuits-2\\\/\"},\"wordCount\":228,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/fr\\\/nouveau-circuit-myanmar-la-plus-belle-des-aventures-en-famille-au-myanmar-10-jours-9-nuits-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/Golden-Rock.jpg\",\"articleSection\":[\"Aventure\",\"Famille\",\"Myanmar - Fran\u00e7ais\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/fr\\\/nouveau-circuit-myanmar-la-plus-belle-des-aventures-en-famille-au-myanmar-10-jours-9-nuits-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/fr\\\/nouveau-circuit-myanmar-la-plus-belle-des-aventures-en-famille-au-myanmar-10-jours-9-nuits-2\\\/\",\"url\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/fr\\\/nouveau-circuit-myanmar-la-plus-belle-des-aventures-en-famille-au-myanmar-10-jours-9-nuits-2\\\/\",\"name\":\"Myanmar\u2019s Finest Family Adventure (10 Days \\\/ 9 Nights)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/fr\\\/nouveau-circuit-myanmar-la-plus-belle-des-aventures-en-famille-au-myanmar-10-jours-9-nuits-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/fr\\\/nouveau-circuit-myanmar-la-plus-belle-des-aventures-en-famille-au-myanmar-10-jours-9-nuits-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/Golden-Rock.jpg\",\"datePublished\":\"2015-05-22T02:06:52+00:00\",\"dateModified\":\"2016-02-09T02:07:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/fr\\\/nouveau-circuit-myanmar-la-plus-belle-des-aventures-en-famille-au-myanmar-10-jours-9-nuits-2\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/fr\\\/nouveau-circuit-myanmar-la-plus-belle-des-aventures-en-famille-au-myanmar-10-jours-9-nuits-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/fr\\\/nouveau-circuit-myanmar-la-plus-belle-des-aventures-en-famille-au-myanmar-10-jours-9-nuits-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/Golden-Rock.jpg\",\"contentUrl\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/Golden-Rock.jpg\",\"width\":580,\"height\":386,\"caption\":\"Golden Rock\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/fr\\\/nouveau-circuit-myanmar-la-plus-belle-des-aventures-en-famille-au-myanmar-10-jours-9-nuits-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nouveau Circuit Myanmar: La plus belle des aventures en famille au Myanmar (10 Jours \\\/ 9 Nuits)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/\",\"name\":\"EXO Travel Blog\",\"description\":\"Travel Made Real\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/#organization\",\"name\":\"EXO Travel Group\",\"url\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Classic-Journeys-1.png\",\"contentUrl\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Classic-Journeys-1.png\",\"width\":900,\"height\":350,\"caption\":\"EXO Travel Group\"},\"image\":{\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ExoTravelGroup\",\"https:\\\/\\\/x.com\\\/EXO_Travel\",\"https:\\\/\\\/www.instagram.com\\\/exotravelgroup\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/exotravel\",\"https:\\\/\\\/www.pinterest.com\\\/exotravel\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/exotravel\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/#\\\/schema\\\/person\\\/25f31f713ccd2c645ee56d896fb33fc0\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1aaf19b4c24206b7a8134ab918439200d6288b7bde9c594c3979468fb18743aa?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1aaf19b4c24206b7a8134ab918439200d6288b7bde9c594c3979468fb18743aa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1aaf19b4c24206b7a8134ab918439200d6288b7bde9c594c3979468fb18743aa?s=96&d=mm&r=g\",\"caption\":\"admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Myanmar\u2019s Finest Family Adventure (10 Days \/ 9 Nights)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.exotravel.com\/blog\/fr\/nouveau-circuit-myanmar-la-plus-belle-des-aventures-en-famille-au-myanmar-10-jours-9-nuits-2\/","og_locale":"en_GB","og_type":"article","og_title":"Myanmar\u2019s Finest Family Adventure (10 Days \/ 9 Nights)","og_description":"Le Myanmar est l\u2019un des pays les plus beaux et les plus passionnants de la r\u00e9gion. C\u2019est le choix de vacances id\u00e9al des familles qui veulent sortir des sentiers battus. Coup\u00e9 du monde pendant des d\u00e9cennies, le pays s\u2019est ouvert r\u00e9cemment et se revendique aujourd\u2019hui comme une destination touristique majeure. Bien que la vie moderne [&hellip;]","og_url":"https:\/\/www.exotravel.com\/blog\/fr\/nouveau-circuit-myanmar-la-plus-belle-des-aventures-en-famille-au-myanmar-10-jours-9-nuits-2\/","og_site_name":"EXO Travel Blog","article_publisher":"https:\/\/www.facebook.com\/ExoTravelGroup","article_published_time":"2015-05-22T02:06:52+00:00","article_modified_time":"2016-02-09T02:07:42+00:00","og_image":[{"width":580,"height":386,"url":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2015\/05\/Golden-Rock.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_creator":"@EXO_Travel","twitter_site":"@EXO_Travel","twitter_misc":{"Written by":"admin","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.exotravel.com\/blog\/fr\/nouveau-circuit-myanmar-la-plus-belle-des-aventures-en-famille-au-myanmar-10-jours-9-nuits-2\/#article","isPartOf":{"@id":"https:\/\/www.exotravel.com\/blog\/fr\/nouveau-circuit-myanmar-la-plus-belle-des-aventures-en-famille-au-myanmar-10-jours-9-nuits-2\/"},"author":{"name":"admin","@id":"https:\/\/www.exotravel.com\/blog\/#\/schema\/person\/25f31f713ccd2c645ee56d896fb33fc0"},"headline":"Nouveau Circuit Myanmar: La plus belle des aventures en famille au Myanmar (10 Jours \/ 9 Nuits)","datePublished":"2015-05-22T02:06:52+00:00","dateModified":"2016-02-09T02:07:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.exotravel.com\/blog\/fr\/nouveau-circuit-myanmar-la-plus-belle-des-aventures-en-famille-au-myanmar-10-jours-9-nuits-2\/"},"wordCount":228,"commentCount":0,"publisher":{"@id":"https:\/\/www.exotravel.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.exotravel.com\/blog\/fr\/nouveau-circuit-myanmar-la-plus-belle-des-aventures-en-famille-au-myanmar-10-jours-9-nuits-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2015\/05\/Golden-Rock.jpg","articleSection":["Aventure","Famille","Myanmar - Fran\u00e7ais"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.exotravel.com\/blog\/fr\/nouveau-circuit-myanmar-la-plus-belle-des-aventures-en-famille-au-myanmar-10-jours-9-nuits-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.exotravel.com\/blog\/fr\/nouveau-circuit-myanmar-la-plus-belle-des-aventures-en-famille-au-myanmar-10-jours-9-nuits-2\/","url":"https:\/\/www.exotravel.com\/blog\/fr\/nouveau-circuit-myanmar-la-plus-belle-des-aventures-en-famille-au-myanmar-10-jours-9-nuits-2\/","name":"Myanmar\u2019s Finest Family Adventure (10 Days \/ 9 Nights)","isPartOf":{"@id":"https:\/\/www.exotravel.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.exotravel.com\/blog\/fr\/nouveau-circuit-myanmar-la-plus-belle-des-aventures-en-famille-au-myanmar-10-jours-9-nuits-2\/#primaryimage"},"image":{"@id":"https:\/\/www.exotravel.com\/blog\/fr\/nouveau-circuit-myanmar-la-plus-belle-des-aventures-en-famille-au-myanmar-10-jours-9-nuits-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2015\/05\/Golden-Rock.jpg","datePublished":"2015-05-22T02:06:52+00:00","dateModified":"2016-02-09T02:07:42+00:00","breadcrumb":{"@id":"https:\/\/www.exotravel.com\/blog\/fr\/nouveau-circuit-myanmar-la-plus-belle-des-aventures-en-famille-au-myanmar-10-jours-9-nuits-2\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.exotravel.com\/blog\/fr\/nouveau-circuit-myanmar-la-plus-belle-des-aventures-en-famille-au-myanmar-10-jours-9-nuits-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.exotravel.com\/blog\/fr\/nouveau-circuit-myanmar-la-plus-belle-des-aventures-en-famille-au-myanmar-10-jours-9-nuits-2\/#primaryimage","url":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2015\/05\/Golden-Rock.jpg","contentUrl":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2015\/05\/Golden-Rock.jpg","width":580,"height":386,"caption":"Golden Rock"},{"@type":"BreadcrumbList","@id":"https:\/\/www.exotravel.com\/blog\/fr\/nouveau-circuit-myanmar-la-plus-belle-des-aventures-en-famille-au-myanmar-10-jours-9-nuits-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.exotravel.com\/blog\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Nouveau Circuit Myanmar: La plus belle des aventures en famille au Myanmar (10 Jours \/ 9 Nuits)"}]},{"@type":"WebSite","@id":"https:\/\/www.exotravel.com\/blog\/#website","url":"https:\/\/www.exotravel.com\/blog\/","name":"EXO Travel Blog","description":"Travel Made Real","publisher":{"@id":"https:\/\/www.exotravel.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.exotravel.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.exotravel.com\/blog\/#organization","name":"EXO Travel Group","url":"https:\/\/www.exotravel.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.exotravel.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2020\/02\/Classic-Journeys-1.png","contentUrl":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2020\/02\/Classic-Journeys-1.png","width":900,"height":350,"caption":"EXO Travel Group"},"image":{"@id":"https:\/\/www.exotravel.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ExoTravelGroup","https:\/\/x.com\/EXO_Travel","https:\/\/www.instagram.com\/exotravelgroup","https:\/\/www.linkedin.com\/company\/exotravel","https:\/\/www.pinterest.com\/exotravel\/","https:\/\/www.youtube.com\/user\/exotravel"]},{"@type":"Person","@id":"https:\/\/www.exotravel.com\/blog\/#\/schema\/person\/25f31f713ccd2c645ee56d896fb33fc0","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/1aaf19b4c24206b7a8134ab918439200d6288b7bde9c594c3979468fb18743aa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1aaf19b4c24206b7a8134ab918439200d6288b7bde9c594c3979468fb18743aa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1aaf19b4c24206b7a8134ab918439200d6288b7bde9c594c3979468fb18743aa?s=96&d=mm&r=g","caption":"admin"}}]}},"_links":{"self":[{"href":"https:\/\/www.exotravel.com\/blog\/wp-json\/wp\/v2\/posts\/14027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.exotravel.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.exotravel.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.exotravel.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.exotravel.com\/blog\/wp-json\/wp\/v2\/comments?post=14027"}],"version-history":[{"count":0,"href":"https:\/\/www.exotravel.com\/blog\/wp-json\/wp\/v2\/posts\/14027\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.exotravel.com\/blog\/wp-json\/wp\/v2\/media\/11282"}],"wp:attachment":[{"href":"https:\/\/www.exotravel.com\/blog\/wp-json\/wp\/v2\/media?parent=14027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.exotravel.com\/blog\/wp-json\/wp\/v2\/categories?post=14027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.exotravel.com\/blog\/wp-json\/wp\/v2\/tags?post=14027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}