{"id":17702,"date":"2018-11-08T08:11:37","date_gmt":"2018-11-08T08:11:37","guid":{"rendered":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2018\/11\/Traditional-vietnamese-street-food1.jpg"},"modified":"2018-11-08T08:11:37","modified_gmt":"2018-11-08T08:11:37","slug":"asian-street-food-traditional-spring-rolls-in-vietnamese-night-market","status":"inherit","type":"attachment","link":"https:\/\/www.exotravel.com\/blog\/en\/the-endless-coastlines-of-central-vietnam\/asian-street-food-traditional-spring-rolls-in-vietnamese-night-market\/","title":{"rendered":"Asian street food. Traditional spring rolls in vietnamese night market"},"author":15,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-17702","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Asian street food. Traditional spring rolls in vietnamese night market - EXO Travel Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2018\/11\/Traditional-vietnamese-street-food1.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Asian street food. Traditional spring rolls in vietnamese night market - EXO Travel Blog\" \/>\n<meta property=\"og:description\" content=\"Asian street food. Traditional spring rolls in vietnamese night market\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2018\/11\/Traditional-vietnamese-street-food1.jpg\" \/>\n<meta property=\"og:site_name\" content=\"EXO Travel Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExoTravelGroup\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2018\/11\/Traditional-vietnamese-street-food1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"978\" \/>\n\t<meta property=\"og:image:height\" content=\"652\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@EXO_Travel\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/Traditional-vietnamese-street-food1.jpg\",\"url\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/Traditional-vietnamese-street-food1.jpg\",\"name\":\"Asian street food. Traditional spring rolls in vietnamese night market - EXO Travel Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/#website\"},\"datePublished\":\"2018-11-08T08:11:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/Traditional-vietnamese-street-food1.jpg#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/Traditional-vietnamese-street-food1.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/Traditional-vietnamese-street-food1.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The Endless Coastlines of Central Vietnam\",\"item\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/en\\\/the-endless-coastlines-of-central-vietnam\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Asian street food. Traditional spring rolls in vietnamese night market\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/\",\"name\":\"EXO Travel Blog\",\"description\":\"Travel Made Real\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/#organization\",\"name\":\"EXO Travel Group\",\"url\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Classic-Journeys-1.png\",\"contentUrl\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Classic-Journeys-1.png\",\"width\":900,\"height\":350,\"caption\":\"EXO Travel Group\"},\"image\":{\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ExoTravelGroup\",\"https:\\\/\\\/x.com\\\/EXO_Travel\",\"https:\\\/\\\/www.instagram.com\\\/exotravelgroup\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/exotravel\",\"https:\\\/\\\/www.pinterest.com\\\/exotravel\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/exotravel\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Asian street food. Traditional spring rolls in vietnamese night market - EXO Travel Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2018\/11\/Traditional-vietnamese-street-food1.jpg","og_locale":"en_GB","og_type":"article","og_title":"Asian street food. Traditional spring rolls in vietnamese night market - EXO Travel Blog","og_description":"Asian street food. Traditional spring rolls in vietnamese night market","og_url":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2018\/11\/Traditional-vietnamese-street-food1.jpg","og_site_name":"EXO Travel Blog","article_publisher":"https:\/\/www.facebook.com\/ExoTravelGroup","og_image":[{"width":978,"height":652,"url":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2018\/11\/Traditional-vietnamese-street-food1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@EXO_Travel","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2018\/11\/Traditional-vietnamese-street-food1.jpg","url":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2018\/11\/Traditional-vietnamese-street-food1.jpg","name":"Asian street food. Traditional spring rolls in vietnamese night market - EXO Travel Blog","isPartOf":{"@id":"https:\/\/www.exotravel.com\/blog\/#website"},"datePublished":"2018-11-08T08:11:37+00:00","breadcrumb":{"@id":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2018\/11\/Traditional-vietnamese-street-food1.jpg#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2018\/11\/Traditional-vietnamese-street-food1.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2018\/11\/Traditional-vietnamese-street-food1.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.exotravel.com\/blog\/en\/home\/"},{"@type":"ListItem","position":2,"name":"The Endless Coastlines of Central Vietnam","item":"https:\/\/www.exotravel.com\/blog\/en\/the-endless-coastlines-of-central-vietnam\/"},{"@type":"ListItem","position":3,"name":"Asian street food. Traditional spring rolls in vietnamese night market"}]},{"@type":"WebSite","@id":"https:\/\/www.exotravel.com\/blog\/#website","url":"https:\/\/www.exotravel.com\/blog\/","name":"EXO Travel Blog","description":"Travel Made Real","publisher":{"@id":"https:\/\/www.exotravel.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.exotravel.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.exotravel.com\/blog\/#organization","name":"EXO Travel Group","url":"https:\/\/www.exotravel.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.exotravel.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2020\/02\/Classic-Journeys-1.png","contentUrl":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2020\/02\/Classic-Journeys-1.png","width":900,"height":350,"caption":"EXO Travel Group"},"image":{"@id":"https:\/\/www.exotravel.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ExoTravelGroup","https:\/\/x.com\/EXO_Travel","https:\/\/www.instagram.com\/exotravelgroup","https:\/\/www.linkedin.com\/company\/exotravel","https:\/\/www.pinterest.com\/exotravel\/","https:\/\/www.youtube.com\/user\/exotravel"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2018\/11\/Traditional-vietnamese-street-food1.jpg'><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2018\/11\/Traditional-vietnamese-street-food1-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2018\/11\/Traditional-vietnamese-street-food1-300x200.jpg 300w, https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2018\/11\/Traditional-vietnamese-street-food1-600x400.jpg 600w, https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2018\/11\/Traditional-vietnamese-street-food1.jpg 978w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Asian street food. Traditional spring rolls in vietnamese night market<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":978,"height":652,"file":"2018\/11\/Traditional-vietnamese-street-food1.jpg","sizes":{"thumbnail":{"file":"Traditional-vietnamese-street-food1-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2018\/11\/Traditional-vietnamese-street-food1-150x150.jpg"},"medium":{"file":"Traditional-vietnamese-street-food1-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2018\/11\/Traditional-vietnamese-street-food1-300x200.jpg"},"blog-thumb-vertical":{"file":"Traditional-vietnamese-street-food1-400x380.jpg","width":400,"height":380,"mime_type":"image\/jpeg","source_url":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2018\/11\/Traditional-vietnamese-street-food1-400x380.jpg"},"blog-thumb-2column-sidebar":{"file":"Traditional-vietnamese-street-food1-409x237.jpg","width":409,"height":237,"mime_type":"image\/jpeg","source_url":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2018\/11\/Traditional-vietnamese-street-food1-409x237.jpg"},"blog-thumb-widget":{"file":"Traditional-vietnamese-street-food1-90x70.jpg","width":90,"height":70,"mime_type":"image\/jpeg","source_url":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2018\/11\/Traditional-vietnamese-street-food1-90x70.jpg"},"thumbnail@2x":{"file":"Traditional-vietnamese-street-food1-300x300.jpg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2018\/11\/Traditional-vietnamese-street-food1-300x300.jpg"},"medium@2x":{"file":"Traditional-vietnamese-street-food1-600x400.jpg","width":600,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2018\/11\/Traditional-vietnamese-street-food1-600x400.jpg"},"blog-thumb-vertical@2x":{"file":"Traditional-vietnamese-street-food1-800x652.jpg","width":800,"height":652,"mime_type":"image\/jpeg","source_url":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2018\/11\/Traditional-vietnamese-street-food1-800x652.jpg"},"blog-thumb-2column-sidebar@2x":{"file":"Traditional-vietnamese-street-food1-818x474.jpg","width":818,"height":474,"mime_type":"image\/jpeg","source_url":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2018\/11\/Traditional-vietnamese-street-food1-818x474.jpg"},"blog-thumb-widget@2x":{"file":"Traditional-vietnamese-street-food1-180x140.jpg","width":180,"height":140,"mime_type":"image\/jpeg","source_url":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2018\/11\/Traditional-vietnamese-street-food1-180x140.jpg"},"full":{"file":"Traditional-vietnamese-street-food1.jpg","width":978,"height":652,"mime_type":"image\/jpeg","source_url":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2018\/11\/Traditional-vietnamese-street-food1.jpg"}},"image_meta":{"aperture":"0","credit":"Getty Images\/iStockphoto","camera":"","caption":"Asian street food. Traditional spring rolls in vietnamese night market","created_timestamp":"0","copyright":"Gilitukha","focal_length":"0","iso":"0","shutter_speed":"0","title":"Asian street food. Traditional spring rolls in vietnamese night market","orientation":"0","keywords":[]}},"post":17698,"source_url":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2018\/11\/Traditional-vietnamese-street-food1.jpg","_links":{"self":[{"href":"https:\/\/www.exotravel.com\/blog\/wp-json\/wp\/v2\/media\/17702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.exotravel.com\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.exotravel.com\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.exotravel.com\/blog\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.exotravel.com\/blog\/wp-json\/wp\/v2\/comments?post=17702"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":17698,"href":"https:\/\/www.exotravel.com\/blog\/wp-json\/wp\/v2\/posts\/17698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}