{"id":16195,"date":"2017-11-17T09:39:31","date_gmt":"2017-11-17T09:39:31","guid":{"rendered":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2017\/11\/beach-534626.jpg"},"modified":"2017-11-17T09:39:31","modified_gmt":"2017-11-17T09:39:31","slug":"beach-534626","status":"inherit","type":"attachment","link":"https:\/\/www.exotravel.com\/blog\/en\/water-a-natural-lure-to-asia\/beach-534626\/","title":{"rendered":"beach-534626"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-16195","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>beach-534626 - EXO Travel Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2017\/11\/beach-534626.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"beach-534626 - EXO Travel Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2017\/11\/beach-534626.jpg\" \/>\n<meta property=\"og:site_name\" content=\"EXO Travel Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExoTravelGroup\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2017\/11\/beach-534626-1024x768.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@EXO_Travel\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/beach-534626.jpg\",\"url\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/beach-534626.jpg\",\"name\":\"beach-534626 - EXO Travel Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/#website\"},\"datePublished\":\"2017-11-17T09:39:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/beach-534626.jpg#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/beach-534626.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/beach-534626.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Water: A Natural Lure to Asia\",\"item\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/en\\\/water-a-natural-lure-to-asia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"beach-534626\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/\",\"name\":\"EXO Travel Blog\",\"description\":\"Travel Made Real\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/#organization\",\"name\":\"EXO Travel Group\",\"url\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Classic-Journeys-1.png\",\"contentUrl\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Classic-Journeys-1.png\",\"width\":900,\"height\":350,\"caption\":\"EXO Travel Group\"},\"image\":{\"@id\":\"https:\\\/\\\/www.exotravel.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ExoTravelGroup\",\"https:\\\/\\\/x.com\\\/EXO_Travel\",\"https:\\\/\\\/www.instagram.com\\\/exotravelgroup\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/exotravel\",\"https:\\\/\\\/www.pinterest.com\\\/exotravel\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/exotravel\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"beach-534626 - EXO Travel Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2017\/11\/beach-534626.jpg","og_locale":"en_GB","og_type":"article","og_title":"beach-534626 - EXO Travel Blog","og_url":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2017\/11\/beach-534626.jpg","og_site_name":"EXO Travel Blog","article_publisher":"https:\/\/www.facebook.com\/ExoTravelGroup","og_image":[{"width":1024,"height":768,"url":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2017\/11\/beach-534626-1024x768.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@EXO_Travel","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2017\/11\/beach-534626.jpg","url":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2017\/11\/beach-534626.jpg","name":"beach-534626 - EXO Travel Blog","isPartOf":{"@id":"https:\/\/www.exotravel.com\/blog\/#website"},"datePublished":"2017-11-17T09:39:31+00:00","breadcrumb":{"@id":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2017\/11\/beach-534626.jpg#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2017\/11\/beach-534626.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2017\/11\/beach-534626.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.exotravel.com\/blog\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Water: A Natural Lure to Asia","item":"https:\/\/www.exotravel.com\/blog\/en\/water-a-natural-lure-to-asia\/"},{"@type":"ListItem","position":3,"name":"beach-534626"}]},{"@type":"WebSite","@id":"https:\/\/www.exotravel.com\/blog\/#website","url":"https:\/\/www.exotravel.com\/blog\/","name":"EXO Travel Blog","description":"Travel Made Real","publisher":{"@id":"https:\/\/www.exotravel.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.exotravel.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.exotravel.com\/blog\/#organization","name":"EXO Travel Group","url":"https:\/\/www.exotravel.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.exotravel.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2020\/02\/Classic-Journeys-1.png","contentUrl":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2020\/02\/Classic-Journeys-1.png","width":900,"height":350,"caption":"EXO Travel Group"},"image":{"@id":"https:\/\/www.exotravel.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ExoTravelGroup","https:\/\/x.com\/EXO_Travel","https:\/\/www.instagram.com\/exotravelgroup","https:\/\/www.linkedin.com\/company\/exotravel","https:\/\/www.pinterest.com\/exotravel\/","https:\/\/www.youtube.com\/user\/exotravel"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2017\/11\/beach-534626.jpg'><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2017\/11\/beach-534626-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2017\/11\/beach-534626-300x225.jpg 300w, https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2017\/11\/beach-534626-1024x768.jpg 1024w, https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2017\/11\/beach-534626-600x450.jpg 600w, https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2017\/11\/beach-534626-2048x1536.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":3648,"height":2736,"file":"2017\/11\/beach-534626.jpg","sizes":{"thumbnail":{"file":"beach-534626-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2017\/11\/beach-534626-150x150.jpg"},"medium":{"file":"beach-534626-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2017\/11\/beach-534626-300x225.jpg"},"large":{"file":"beach-534626-1024x768.jpg","width":1024,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2017\/11\/beach-534626-1024x768.jpg"},"blog-thumb":{"file":"beach-534626-1140x660.jpg","width":1140,"height":660,"mime_type":"image\/jpeg","source_url":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2017\/11\/beach-534626-1140x660.jpg"},"blog-thumb-vertical":{"file":"beach-534626-400x380.jpg","width":400,"height":380,"mime_type":"image\/jpeg","source_url":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2017\/11\/beach-534626-400x380.jpg"},"blog-thumb-2column-sidebar":{"file":"beach-534626-409x237.jpg","width":409,"height":237,"mime_type":"image\/jpeg","source_url":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2017\/11\/beach-534626-409x237.jpg"},"blog-thumb-widget":{"file":"beach-534626-90x70.jpg","width":90,"height":70,"mime_type":"image\/jpeg","source_url":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2017\/11\/beach-534626-90x70.jpg"},"thumbnail@2x":{"file":"beach-534626-300x300.jpg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2017\/11\/beach-534626-300x300.jpg"},"medium@2x":{"file":"beach-534626-600x450.jpg","width":600,"height":450,"mime_type":"image\/jpeg","source_url":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2017\/11\/beach-534626-600x450.jpg"},"large@2x":{"file":"beach-534626-2048x1536.jpg","width":2048,"height":1536,"mime_type":"image\/jpeg","source_url":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2017\/11\/beach-534626-2048x1536.jpg"},"blog-thumb@2x":{"file":"beach-534626-2280x1320.jpg","width":2280,"height":1320,"mime_type":"image\/jpeg","source_url":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2017\/11\/beach-534626-2280x1320.jpg"},"blog-thumb-vertical@2x":{"file":"beach-534626-800x760.jpg","width":800,"height":760,"mime_type":"image\/jpeg","source_url":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2017\/11\/beach-534626-800x760.jpg"},"blog-thumb-2column-sidebar@2x":{"file":"beach-534626-818x474.jpg","width":818,"height":474,"mime_type":"image\/jpeg","source_url":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2017\/11\/beach-534626-818x474.jpg"},"blog-thumb-widget@2x":{"file":"beach-534626-180x140.jpg","width":180,"height":140,"mime_type":"image\/jpeg","source_url":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2017\/11\/beach-534626-180x140.jpg"},"full":{"file":"beach-534626.jpg","width":3648,"height":2736,"mime_type":"image\/jpeg","source_url":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2017\/11\/beach-534626.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":16189,"source_url":"https:\/\/www.exotravel.com\/blog\/wp-content\/uploads\/2017\/11\/beach-534626.jpg","_links":{"self":[{"href":"https:\/\/www.exotravel.com\/blog\/wp-json\/wp\/v2\/media\/16195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.exotravel.com\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.exotravel.com\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.exotravel.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.exotravel.com\/blog\/wp-json\/wp\/v2\/comments?post=16195"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":16189,"href":"https:\/\/www.exotravel.com\/blog\/wp-json\/wp\/v2\/posts\/16189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}